{"id":580,"date":"2015-06-18T16:32:16","date_gmt":"2015-06-18T14:32:16","guid":{"rendered":"https:\/\/web2.acc-solutions.ch\/?p=580"},"modified":"2020-11-24T10:14:43","modified_gmt":"2020-11-24T09:14:43","slug":"acc-solutions-ag-neuer-firmenauftritt","status":"publish","type":"post","link":"https:\/\/www.acc-solutions.ch\/en\/acc-solutions-ag-neuer-firmenauftritt\/","title":{"rendered":"acc solutions AG \u2013 neuer Firmenauftritt"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"580\" class=\"elementor elementor-580\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e49b1d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e49b1d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01a2932\" data-id=\"01a2932\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88f6465 elementor-widget elementor-widget-spacer\" data-id=\"88f6465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa8268a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa8268a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-233e28d\" data-id=\"233e28d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-924f597 elementor-widget elementor-widget-heading\" data-id=\"924f597\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">acc solutions AG \u2013 neuer Firmenauftritt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e62ba7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e62ba7f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-910a49a\" data-id=\"910a49a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b42bb39 elementor-widget elementor-widget-spacer\" data-id=\"b42bb39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0789e82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0789e82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-86b9adf\" data-id=\"86b9adf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b08af0 elementor-widget elementor-widget-text-editor\" data-id=\"7b08af0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.acc-solutions.ch\/en\/\" target=\"_blank\" rel=\"noopener\">acc solutions<\/a> blickt auf eine Erfolgsgeschichte zur\u00fcck, die von Kundenorientiertheit, Prozess- und IT-Wissen gepr\u00e4gt ist. 2007 starteten <a href=\"https:\/\/www.linkedin.com\/in\/rogermuller\/\" target=\"_blank\" rel=\"noopener\">Roger M\u00fcller (CEO)<\/a> und <a href=\"https:\/\/www.linkedin.com\/in\/dominikblunk\/\" target=\"_blank\" rel=\"noopener\">Dominik Blunk (CTO)<\/a> das Unternehmen mit ersten Software- und Beratungsprojekten. Heute, rund sieben Jahre sp\u00e4ter bietet das gewachsene Unternehmen von der umfassenden Prozess- und Organisationsberatung bis hin zur bed\u00fcrfnisgerechten Umsetzung der erarbeiteten L\u00f6sungen alles aus einer Hand.<\/p><p>Damit dem gr\u00f6sseren Angebot von acc solutions Rechnung getragen wird, wurde der Firmenauftritt gemeinsam mit Tatort Bern GmbH und Wohnzeit \u00fcberarbeitet. Vielen Dank f\u00fcr die termingerechte und kostenbewusste Zusammenarbeit.<\/p><p>Das neue Logo und der verk\u00fcrzte Name \u201cacc solutions\u201c soll die Firmenphilosophie und Angebotsstruktur des Unternehmens klarer kommunizieren und findet seinen Ursprung in der fr\u00fcheren Firmenbezeichnung.<\/p><p>Die Farbe Blau symbolisiert die tiefgehende und sorgf\u00e4ltige Unterst\u00fctzung f\u00fcr Kunden in der L\u00f6sungsfindung rund um Gesch\u00e4ftsprozesse.\u00a0\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de3075e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de3075e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cfc904d\" data-id=\"cfc904d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df5088d elementor-widget elementor-widget-image\" data-id=\"df5088d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"740\" height=\"416\" src=\"https:\/\/www.acc-solutions.ch\/wp-content\/uploads\/2015\/06\/underwater-2615376-1024x576.jpg\" class=\"attachment-large size-large wp-image-5547\" alt=\"\" srcset=\"https:\/\/www.acc-solutions.ch\/wp-content\/uploads\/2015\/06\/underwater-2615376-1024x576.jpg 1024w, https:\/\/www.acc-solutions.ch\/wp-content\/uploads\/2015\/06\/underwater-2615376-300x169.jpg 300w, https:\/\/www.acc-solutions.ch\/wp-content\/uploads\/2015\/06\/underwater-2615376-768x432.jpg 768w, https:\/\/www.acc-solutions.ch\/wp-content\/uploads\/2015\/06\/underwater-2615376-1536x864.jpg 1536w, https:\/\/www.acc-solutions.ch\/wp-content\/uploads\/2015\/06\/underwater-2615376-2048x1152.jpg 2048w, https:\/\/www.acc-solutions.ch\/wp-content\/uploads\/2015\/06\/underwater-2615376-16x9.jpg 16w, https:\/\/www.acc-solutions.ch\/wp-content\/uploads\/2015\/06\/underwater-2615376-1440x810.jpg 1440w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91d31e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91d31e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae0175c\" data-id=\"ae0175c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6630c2d elementor-widget elementor-widget-text-editor\" data-id=\"6630c2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mit akkuratem Projekt- und Changemanagement, als auch teamgerechten Schulungen und Trainings vor Ort werden die L\u00f6sungen erfolgreich umgesetzt. Die Farbe Gr\u00fcn steht f\u00fcr die fortw\u00e4hrende Entwicklung der entstandenen L\u00f6sungen. Mit dem modular aufgebauten Service Champion (SaaS) bietet acc solutions massgeschneiderte L\u00f6sungen, welche der stets herausfordernden Umwelt gerecht werden. Kundengerechte solutions entstehen \u00fcber das ganze Angebot hinweg.<\/p><p>Roger M\u00fcller (CEO) \u00fcber acc solutions:<\/p><p>\u201eWir suchen keine Kunden f\u00fcr unsere L\u00f6sungen,<br \/>sondern finden L\u00f6sungen f\u00fcr unsere Kunden.<\/p><p>Wir entwickeln f\u00fcr sie nicht einfach Software,<br \/>sondern optimieren ihre gesamten Unternehmensprozesse.<br \/>Daf\u00fcr gehen wir nicht nur eine Extrameile,<br \/>sondern laufen einen Extramarathon.<br \/>Weil einzigartige Unternehmen einzigartiges Engagement brauchen.\u201c<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4c71cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4c71cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fbf52c5\" data-id=\"fbf52c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f70ab41 elementor-widget elementor-widget-button\" data-id=\"f70ab41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.acc-solutions.ch\/en\/firma\/#kontakt\" target=\"_blank\" id=\"contact-us-graphics\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontaktieren Sie uns<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>acc solutions AG \u2013 neuer Firmenauftritt acc solutions blickt auf eine Erfolgsgeschichte zur\u00fcck, die von Kundenorientiertheit, Prozess- und IT-Wissen gepr\u00e4gt ist. 2007 starteten Roger M\u00fcller (CEO) und Dominik Blunk (CTO) das Unternehmen mit ersten Software- und Beratungsprojekten. Heute, rund sieben Jahre sp\u00e4ter bietet das gewachsene Unternehmen von der umfassenden Prozess- und Organisationsberatung bis hin zur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5542,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,25],"tags":[47,55,54,57,56],"class_list":["post-580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-change","tag-acc-solutions","tag-firmenauftritt","tag-logo","tag-mission","tag-vision"],"_links":{"self":[{"href":"https:\/\/www.acc-solutions.ch\/en\/wp-json\/wp\/v2\/posts\/580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.acc-solutions.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.acc-solutions.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.acc-solutions.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.acc-solutions.ch\/en\/wp-json\/wp\/v2\/comments?post=580"}],"version-history":[{"count":13,"href":"https:\/\/www.acc-solutions.ch\/en\/wp-json\/wp\/v2\/posts\/580\/revisions"}],"predecessor-version":[{"id":5553,"href":"https:\/\/www.acc-solutions.ch\/en\/wp-json\/wp\/v2\/posts\/580\/revisions\/5553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.acc-solutions.ch\/en\/wp-json\/wp\/v2\/media\/5542"}],"wp:attachment":[{"href":"https:\/\/www.acc-solutions.ch\/en\/wp-json\/wp\/v2\/media?parent=580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.acc-solutions.ch\/en\/wp-json\/wp\/v2\/categories?post=580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.acc-solutions.ch\/en\/wp-json\/wp\/v2\/tags?post=580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}